{"id":3157,"date":"2026-04-06T22:11:14","date_gmt":"2026-04-07T03:11:14","guid":{"rendered":"https:\/\/onginnovacionsocial.org\/site\/?p=3157"},"modified":"2026-04-09T22:36:46","modified_gmt":"2026-04-10T03:36:46","slug":"convocatoria-laboral-profesional-en-trabajo-social","status":"publish","type":"post","link":"https:\/\/onginnovacionsocial.org\/site\/2026\/04\/06\/convocatoria-laboral-profesional-en-trabajo-social\/","title":{"rendered":"CONVOCATORIA LABORAL: Profesional en Trabajo Social"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3157\" class=\"elementor elementor-3157\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d90c989 e-flex e-con-boxed e-con e-parent\" data-id=\"d90c989\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18505ae elementor-widget elementor-widget-text-editor\" data-id=\"18505ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong> \ud83c\udf1f \u00a1\u00danete a nuestro equipo en ONG Innovaci\u00f3n Social! \ud83c\udf1f<\/strong><\/p><p><img decoding=\"async\" class=\"alignleft wp-image-3178 size-thumbnail\" src=\"https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-150x150.jpg 150w, https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-300x300.jpg 300w, https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-1024x1024.jpg 1024w, https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-768x768.jpg 768w, https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01.jpg 1458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/p><p style=\"text-align: justify;\">En la <strong>ONG Innovaci\u00f3n Social<\/strong> impulsamos el desarrollo sostenible mediante servicios sociales y financieros innovadores. Buscamos un Trabajador(a) Social con al menos 12 meses de experiencia en programas de ICBF para unirse a nuestro equipo bajo contrato OPS. Si compartes nuestros valores de integridad y responsabilidad social, \u00a1queremos conocer tu talento!<\/p><p style=\"text-align: justify;\">\u00bfEres un profesional apasionado por la protecci\u00f3n y el bienestar social? Estamos buscando talento para transformar vidas.<\/p><ul><li style=\"text-align: justify;\"><strong>Requisitos:<\/strong> Formaci\u00f3n: Profesional en Trabajo Social.<\/li><li style=\"text-align: justify;\"><strong>Experiencia:<\/strong> M\u00ednimo 12 meses de experiencia espec\u00edfica en programas de protecci\u00f3n del ICBF (indispensable).<\/li><\/ul><p>Condiciones del Cargo:<\/p><ul><li><strong>Tipo de contrato:<\/strong> Orden de Prestaci\u00f3n de Servicios (OPS).<\/li><li><strong>Vacantes disponibles:<\/strong> 1.<\/li><\/ul><p style=\"text-align: center;\"><strong>\u00bfC\u00f3mo postularse?<\/strong><\/p><p style=\"text-align: center;\">Env\u00eda tu hoja de vida actualizada al correo: <a href=\"mailto:fundacion@onginnovacionsocial.org\">fundacion@onginnovacionsocial.org<\/a><br \/>Plazo m\u00e1ximo de recepci\u00f3n:<br \/><span style=\"text-decoration: underline;\"><strong>Lunes, 13 de abril de 2026, hasta las 5:00 p.m.<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf1f \u00a1\u00danete a nuestro equipo en ONG Innovaci\u00f3n Social! \ud83c\udf1f En la ONG Innovaci\u00f3n Social impulsamos el desarrollo sostenible mediante servicios sociales y financieros innovadores. Buscamos un Trabajador(a) Social con al menos 12 meses de experiencia en programas de ICBF para unirse a nuestro equipo bajo contrato OPS. Si compartes nuestros valores de integridad y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_joinchat":[],"footnotes":""},"categories":[6],"tags":[20,15,21],"class_list":["post-3157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-convocatoria","tag-onginnovacionsocial","tag-trabajo-social"],"uagb_featured_image_src":{"full":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01.jpg",1458,1458,false],"thumbnail":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-150x150.jpg",150,150,true],"medium":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-300x300.jpg",300,300,true],"medium_large":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-768x768.jpg",768,768,true],"large":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01-1024x1024.jpg",800,800,true],"1536x1536":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01.jpg",1458,1458,false],"2048x2048":["https:\/\/onginnovacionsocial.org\/site\/wp-content\/uploads\/2026\/04\/equipodetrabajo_01.jpg",1458,1458,false]},"uagb_author_info":{"display_name":"adminongis","author_link":"https:\/\/onginnovacionsocial.org\/site\/author\/adminongis\/"},"uagb_comment_info":0,"uagb_excerpt":"\ud83c\udf1f \u00a1\u00danete a nuestro equipo en ONG Innovaci\u00f3n Social! \ud83c\udf1f En la ONG Innovaci\u00f3n Social impulsamos el desarrollo sostenible mediante servicios sociales y financieros innovadores. Buscamos un Trabajador(a) Social con al menos 12 meses de experiencia en programas de ICBF para unirse a nuestro equipo bajo contrato OPS. Si compartes nuestros valores de integridad y&hellip;","_links":{"self":[{"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/posts\/3157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/comments?post=3157"}],"version-history":[{"count":29,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/posts\/3157\/revisions"}],"predecessor-version":[{"id":3190,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/posts\/3157\/revisions\/3190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/media\/3178"}],"wp:attachment":[{"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/media?parent=3157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/categories?post=3157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onginnovacionsocial.org\/site\/wp-json\/wp\/v2\/tags?post=3157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}